{"id":5605,"date":"2021-11-25T13:03:51","date_gmt":"2021-11-25T18:03:51","guid":{"rendered":"https:\/\/www.arboplus.ca\/blog\/?p=5605"},"modified":"2022-04-02T13:54:35","modified_gmt":"2022-04-02T17:54:35","slug":"le-bouleau-a-papier-betula-papyrifera","status":"publish","type":"post","link":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html","title":{"rendered":"Le bouleau \u00e0 papier"},"content":{"rendered":"<h2>Betula papyrifera<\/h2>\n<p>Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada. En effet, pr\u00e9sent dans toutes les r\u00e9gions foresti\u00e8res du Canada et dans les for\u00eats bor\u00e9ales, on peut presque se demander pourquoi il ne serait pas l\u2019embl\u00e8me canadien plut\u00f4t que la feuille d\u2019<a href=\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/erable-rouge-acer-rubrum.html\">\u00e9rable<\/a>\u2026 D\u2019autant plus que, fait bien m\u00e9connu, le bouleau est aussi utilis\u00e9 pour faire un d\u00e9licieux sirop \u00e0 partir de la s\u00e8ve !<\/p>\n<div style=\"text-align: center;\"><a class=\"button green medium\" href=\"http:\/\/www.arboplus.ca\/fr\/estimation-gratuite.html\" target=\"_self\" rel=\"noopener\">Demander l&rsquo;\u00e9valuation de mon bouleau blanc par un arboriculteur <i class=\"fa-chevron-circle-right\"><\/i><\/a><\/div>\n<p>C&rsquo;est un arbre blanc, au feuillage d\u00e9gag\u00e9 et clairsem\u00e9. Il s\u2019agit d\u2019un arbre \u00e0 croissance rapide et qui pourra donc plaire \u00e0 ceux qui veulent un arbre d\u2019ornement plus t\u00f4t que tard. \u00c0 maturit\u00e9, cet arbre peut atteindre les 15 \u00e0 21 m\u00e8tres de hauteur et 14 m\u00e8tres de largeur. En jeunesse, le bouleau \u00e0 papier sera rouge fonc\u00e9, avec un port pyramidal. Plus \u00e2g\u00e9, son \u00e9corce sera d\u2019un blanc \u00e9clatant avec un port plus arrondi. C\u2019est en fait l\u2019\u00e9corce de cet arbre qui fait toute la distinction. Il peut arriver qu\u2019on le confonde avec le peuplier, mais ce dernier est d\u2019une couleur plut\u00f4t grise, et son \u00e9corce ne s\u2019exfolie pas comme celle du bouleau. Cette caract\u00e9ristique fait tout le charme de cet arbre. On peut \u00ab l\u2019\u00e9plucher \u00bb en grandes feuilles pour d\u00e9couvrir une couleur jaune p\u00e2le en dessous de l\u2019\u00e9corce superficielle.<\/p>\n<div id=\"attachment_5608\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-5608\" class=\"size-full wp-image-5608\" src=\"http:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/bouleau-blanc-ecorce-blanche-tronc-flexible.jpg\" alt=\"L'\u00e9corce du bouleau \u00e0 papier mature est d'un blanc pur\" width=\"640\" height=\"427\" \/><p id=\"caption-attachment-5608\" class=\"wp-caption-text\">L&rsquo;\u00e9corce du bouleau \u00e0 papier mature est d&rsquo;un blanc pur<\/p><\/div>\n<p>L\u2019\u00e9corce du bouleau blanc est particuli\u00e8rement recherch\u00e9e par les chasseurs qui connaissent ses propri\u00e9t\u00e9s d\u2019allumage de feu, car, \u00e9tant un bois gras, il demeure inflammable m\u00eame humide. Autrefois, les autochtones utilisaient l\u2019\u00e9corce du bouleau \u00e0 papier pour la confection de toutes sortes d\u2019objets, notamment pour la construction de cano\u00ebs.<\/p>\n<p>La <a href=\"https:\/\/www.arboplus.ca\/blog\/arboriculture\/comment-identifier-un-arbre-avec-ses-feuilles.html\">feuille du bouleau<\/a> est de forme ovale, presque triangulaire, et doublement dent\u00e9e. Avec du recul, on per\u00e7oit le feuillage d\u2019aspect l\u00e9ger et clairsem\u00e9, tout le contraire du feuillage dense et \u00e9pais de l\u2019\u00e9rable de Norv\u00e8ge. \u00c0 l\u2019automne, ses feuilles tendront vers le jaune.<\/p>\n<div id=\"attachment_5609\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5609\" class=\"size-full wp-image-5609\" src=\"http:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/feuilles-du-bouleau-ovales-doublement-dentees.jpg\" alt=\"Bouleau blanc - Feuilles ovales et doublement dent\u00e9es\" width=\"640\" height=\"480\" \/><p id=\"caption-attachment-5609\" class=\"wp-caption-text\">Bouleau blanc &#8211; Feuilles ovales et doublement dent\u00e9es<\/p><\/div>\n<h2>Les fruits et la faune<\/h2>\n<p>Les fruits et les fleurs ne pr\u00e9sentent pas vraiment d\u2019int\u00e9r\u00eats ornementaux, pas plus que les samares de l&rsquo;<a href=\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/erable-argente-acer-saccharinum.html\">\u00e9rable<\/a>. Pourtant, \u00e9tant un <a href=\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/arbres-indigenes.html\">arbre indig\u00e8ne du Qu\u00e9bec<\/a>, cet arbre saura contribuer au bien \u00eatre de la faune, ne serait-ce que celui des <a href=\"https:\/\/www.arboplus.ca\/blog\/developpement-durable\/lutte-biologique-contre-les-insectes.html\">insectes<\/a>.<\/p>\n<div id=\"attachment_5610\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5610\" class=\"size-full wp-image-5610\" src=\"http:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/fruits-du-bouleau-a-papier.jpg\" alt=\"Fruits du bouleau \u00e0 papier du Canada\" width=\"640\" height=\"640\" \/><p id=\"caption-attachment-5610\" class=\"wp-caption-text\">Fruits du bouleau \u00e0 papier du Canada<\/p><\/div>\n<h2>Conditions optimales<\/h2>\n<p>Il s\u2019agit d\u2019un arbre parfait pour l\u2019ornement paysager, mais il supporte mal les conditions urbaines. Il est ad\u00e9quat en vertu de sa croissance rapide et de son feuillage l\u00e9ger, n\u00e9cessitant peu d\u2019entretien. Il pr\u00e9f\u00e8re <a href=\"https:\/\/www.arboplus.ca\/blog\/developpement-durable\/le-sol-une-vie-en-soi.html\">un sol<\/a> assez sec, voir sableux. En revanche, le bouleau \u00e0 papier est un arbre qui supportera tr\u00e8s mal la pollution, en particulier le sel de d\u00e9gla\u00e7age. Les <a href=\"https:\/\/www.arboplus.ca\/blog\/developpement-durable\/proteger-arbres-lors-travaux-de-construction.html\">travaux de construction<\/a> peuvent le stresser et mener \u00e0 son d\u00e9p\u00e9rissement, de m\u00eame que pour le compactage du sol.<\/p>\n<h2>\u00c9lagage et entretien du bouleau blanc<\/h2>\n<p>On sugg\u00e8re de faire une <a href=\"https:\/\/www.arboplus.ca\/blog\/arboriculture\/taille-dun-jeune-arbre.html\">taille de formation de l\u2019arbre en bas \u00e2ge<\/a>. Du reste, simplement assurer un sol en sant\u00e9 et <a href=\"https:\/\/www.arboplus.ca\/blog\/developpement-durable\/elagage-des-arbres-les-bonnes-et-les-mauvaises-pratiques.html\">\u00e9laguer les branches<\/a> qui nuisent \u00e0 son environnement urbain. Il produit une quantit\u00e9 non n\u00e9gligeable de bois mort, qu\u2019il convient d\u2019enlever environ aux trois ans pour la s\u00e9curit\u00e9 et pour l\u2019esth\u00e9tique.<\/p>\n<div id=\"attachment_5611\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5611\" class=\"size-full wp-image-5611\" src=\"http:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/betula-papyrifera-en-autome-a-laval.jpg\" alt=\"Betula papyrifera en automne \u00e0 Laval\" width=\"640\" height=\"428\" \/><p id=\"caption-attachment-5611\" class=\"wp-caption-text\">Betula papyrifera en automne \u00e0 Laval<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>\u00c9tant d\u2019un bois assez mou, on voudra \u00e9viter que l\u2019arbre ne penche vers les structures importantes, comme les<a href=\"https:\/\/www.arboplus.ca\/blog\/arboriculture\/quand-appeler-hydro-quebec.html\"> lignes \u00e9lectriques<\/a> par exemple. Ceci advient g\u00e9n\u00e9ralement suite \u00e0 des verglas qui provoquent des courbures s\u00e9v\u00e8res au tronc du bouleau \u00e0 papier, et l\u2019arbre peut rester dans cet \u00e9tat tout l\u2019hiver. On peut donc opter pour un \u00e9lagage qui vise \u00e0 all\u00e9ger les endroits de l\u2019arbre o\u00f9 la charpente est plus lourde. Toutefois, l\u2019haubanage est l\u2019option la plus durable et la moins dommageable car elle ne n\u00e9cessite pas l\u2019enl\u00e8vement inutile de masse vivante de l\u2019arbre.<\/p>\n<div style=\"text-align: center;\"><a class=\"button green medium\" href=\"http:\/\/www.arboplus.ca\/fr\/estimation-gratuite.html\" target=\"_self\" rel=\"noopener\">Planifier un rendez-vous avec un arboriste-expert <i class=\"fa-chevron-circle-right\"><\/i><\/a><\/div>\n<h2>Maladies<\/h2>\n<p>Bien que sensible aux conditions urbaines, les maladies du bouleau blanc sont relativement rares. On note une l\u00e9g\u00e8re sensibilit\u00e9 aux chancres, de m\u00eame qu\u2019\u00e0 certains insectes comme l\u2019<a href=\"https:\/\/www.arboplus.ca\/blog\/arboriculture\/lagrile-du-frene.html\">agrile<\/a> du bouleau, la mineuse ainsi que la porte-case du bouleau.<\/p>\n<h2>Bibliographie<\/h2>\n<ul>\n<li>Bertrand, Dumont. Guide des arbres, arbustes et conif\u00e8res pour le Qu\u00e9bec. Broquet, 2005.<\/li>\n<li>Farrar, John Laird. Les arbres du Canada. Les Editions Fides, 1996.<\/li>\n<li>(forester.), Michael D. Williams. Guide D\u2019identification des Arbres du Qu\u00e9bec et de L\u2019est de L\u2019Am\u00e9rique du Nord. Broquet, Incorporated, 2008.<\/li>\n<li>Hodgson, Larry. Arbres. Saint-Constant, Qc: Broquet, 2012.<\/li>\n<li>Langlais, Guy. La taille des arbres ornementaux. Saint-Constant, Qc: Broquet, 2002.<\/li>\n<li>Marie-Fleurette, Beaudoin, Gaudet Martin, Rocray Pierre-\u00c9mile, et Michel Labrecque. Les arbres de Montr\u00e9al. Fides, 1997.<\/li>\n<li>Pellerin, Gervais, et Hydro-Qu\u00e9bec. R\u00e9pertoire des Arbres et Arbustes Ornementaux: 1760 Esp\u00e8ces et Vari\u00e9t\u00e9s de V\u00e9g\u00e9taux du Qu\u00e9bec. Gouvernement du Quebec, publications vendues, 2010.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada. En effet, pr\u00e9sent dans toutes les r\u00e9gions foresti\u00e8res du Canada et dans les for\u00eats bor\u00e9ales.<\/p>\n","protected":false},"author":2,"featured_media":5613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[4052,4028,4016,283,2329,4055,4031,837,4007,4019,4029,1619,4006,4008,4051,784,4027,1212,1917,4032,4033,4021,4048,3534,4013,2783,4035,305,4026,4025,58,4043,4012,768,66,1380,4015,4038,459,4034,229,4011,2965,231,4023,3421,4054,673,818,4030,162,4036,3592,3624,4053,3102,4056,4022,4057,2830,2831,4047,4049,4009,4037,1982,4044,4010,2834,4018,1775,502,4050,687,4046,4040,4041,4014,4017,4045,4020,3328,4039,4042,4024,3589,680],"class_list":["post-5605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essences-arbres","tag-agrile-du-bouleau","tag-allumage-de-feu","tag-arbre-a-croissance-rapide","tag-arbre-indigene","tag-arbre-indigene-du-quebec","tag-arbustes-et-coniferes-pour-le-quebec","tag-autochtones","tag-automne","tag-betula-papyrifera","tag-blanc-eclatant","tag-bois-gras","tag-bouleau","tag-bouleau-a-papier","tag-bouleau-blanc","tag-certains-insectes","tag-charpente","tag-chasseurs","tag-compactage-du-sol","tag-conditions-urbaines","tag-confection-de-toutes-sortes-dobjets","tag-construction-de-canoes","tag-couleur-plutot-grise","tag-courbures-severes-au-tronc","tag-croissance-rapide","tag-delicieux-sirop","tag-deperissement","tag-doublement-dentee","tag-ecorce","tag-ecorce-du-bouleau-blanc","tag-ecorce-superficielle","tag-elagage","tag-elaguer-les-branches","tag-embleme-canadien","tag-environnement-urbain","tag-erable-de-norvege","tag-especes-et-varietes-de-vegetaux-du-quebec","tag-feuillage-degage-et-clairseme","tag-feuillage-leger","tag-feuille-derable","tag-feuille-du-bouleau","tag-fleurs","tag-forets-boreales","tag-forme-ovale","tag-fruits","tag-grandes-feuilles","tag-guide-didentification-des-arbres-du-quebec","tag-guide-des-arbres","tag-haubanage","tag-hiver","tag-inflammable-meme-humide","tag-insectes","tag-interets-ornementaux","tag-lesthetique","tag-la-faune","tag-la-mineuse","tag-la-securite","tag-la-taille-des-arbres-ornementaux","tag-le-charme-de-cet-arbre","tag-les-arbres-de-montreal","tag-les-arbres-du-canada","tag-les-editions-fides","tag-les-lignes-electriques","tag-maladies-du-bouleau-blanc","tag-omnipresent-au-canada","tag-ornement-paysager","tag-peuplier","tag-quantite-non-negligeable-de-bois-mort","tag-regions-forestieres-du-canada","tag-repertoire-des-arbres-et-arbustes-ornementaux","tag-rouge-fonce","tag-samares","tag-sel-de-deglacage","tag-sensibilite-aux-chancres","tag-seve","tag-structures-importantes","tag-supportera-tres-mal-la-pollution","tag-travaux-de-construction","tag-un-arbre-blanc","tag-un-arbre-dornement","tag-un-bois-assez-mou","tag-un-port-plus-arrondi","tag-un-port-pyramidal","tag-un-sol-assez-sec","tag-un-sol-en-sante","tag-une-couleur-jaune-pale","tag-une-taille-de-formation","tag-verglas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le bouleau \u00e0 papier - Betula papyrifera - Arboplus<\/title>\n<meta name=\"description\" content=\"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le bouleau \u00e0 papier - Betula papyrifera - Arboplus\" \/>\n<meta property=\"og:description\" content=\"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html\" \/>\n<meta property=\"og:site_name\" content=\"Arboplus\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T18:03:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-02T17:54:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominic Perugino\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominic Perugino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html\",\"url\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html\",\"name\":\"Le bouleau \u00e0 papier - Betula papyrifera - Arboplus\",\"isPartOf\":{\"@id\":\"https:\/\/www.arboplus.ca\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg\",\"datePublished\":\"2021-11-25T18:03:51+00:00\",\"dateModified\":\"2022-04-02T17:54:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/c4e4c82ad12349aafba47d44193f5540\"},\"description\":\"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage\",\"url\":\"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg\",\"contentUrl\":\"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Betula papyrifera - Bouleau blanc du Canada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.arboplus.ca\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le bouleau \u00e0 papier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/#website\",\"url\":\"https:\/\/www.arboplus.ca\/blog\/\",\"name\":\"Arboplus\",\"description\":\"Magazine arboricole\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arboplus.ca\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/c4e4c82ad12349aafba47d44193f5540\",\"name\":\"Dominic Perugino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0027ec1e3f6852cb4655750d4303f090?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0027ec1e3f6852cb4655750d4303f090?s=96&d=mm&r=g\",\"caption\":\"Dominic Perugino\"},\"url\":\"https:\/\/www.arboplus.ca\/blog\/author\/dominic-perugino\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le bouleau \u00e0 papier - Betula papyrifera - Arboplus","description":"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html","og_locale":"fr_CA","og_type":"article","og_title":"Le bouleau \u00e0 papier - Betula papyrifera - Arboplus","og_description":"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.","og_url":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html","og_site_name":"Arboplus","article_published_time":"2021-11-25T18:03:51+00:00","article_modified_time":"2022-04-02T17:54:35+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg","type":"image\/jpeg"}],"author":"Dominic Perugino","twitter_misc":{"\u00c9crit par":"Dominic Perugino","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html","url":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html","name":"Le bouleau \u00e0 papier - Betula papyrifera - Arboplus","isPartOf":{"@id":"https:\/\/www.arboplus.ca\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage"},"image":{"@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage"},"thumbnailUrl":"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg","datePublished":"2021-11-25T18:03:51+00:00","dateModified":"2022-04-02T17:54:35+00:00","author":{"@id":"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/c4e4c82ad12349aafba47d44193f5540"},"description":"Aussi appel\u00e9 le bouleau blanc, le bouleau \u00e0 papier est un arbre indig\u00e8ne omnipr\u00e9sent au Canada.","breadcrumb":{"@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#primaryimage","url":"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg","contentUrl":"https:\/\/www.arboplus.ca\/blog\/wp-content\/uploads\/2021\/11\/Betula-papyrifera-bouleau-blanc-du-canada.jpg","width":1920,"height":1080,"caption":"Betula papyrifera - Bouleau blanc du Canada"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arboplus.ca\/blog\/essences-arbres\/le-bouleau-a-papier-betula-papyrifera.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.arboplus.ca\/blog\/"},{"@type":"ListItem","position":2,"name":"Le bouleau \u00e0 papier"}]},{"@type":"WebSite","@id":"https:\/\/www.arboplus.ca\/blog\/#website","url":"https:\/\/www.arboplus.ca\/blog\/","name":"Arboplus","description":"Magazine arboricole","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arboplus.ca\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/c4e4c82ad12349aafba47d44193f5540","name":"Dominic Perugino","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.arboplus.ca\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0027ec1e3f6852cb4655750d4303f090?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0027ec1e3f6852cb4655750d4303f090?s=96&d=mm&r=g","caption":"Dominic Perugino"},"url":"https:\/\/www.arboplus.ca\/blog\/author\/dominic-perugino"}]}},"_links":{"self":[{"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/posts\/5605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/comments?post=5605"}],"version-history":[{"count":5,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/posts\/5605\/revisions"}],"predecessor-version":[{"id":5607,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/posts\/5605\/revisions\/5607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/media\/5613"}],"wp:attachment":[{"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/media?parent=5605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/categories?post=5605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arboplus.ca\/blog\/wp-json\/wp\/v2\/tags?post=5605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}